{"id":2878,"date":"2024-11-05T09:08:27","date_gmt":"2024-11-05T08:08:27","guid":{"rendered":"https:\/\/schloetter-group.com\/zur-feier-von-60-jahren-erfolgreicher-zusammenarbeit\/"},"modified":"2024-11-05T09:08:27","modified_gmt":"2024-11-05T08:08:27","slug":"zur-feier-von-60-jahren-erfolgreicher-zusammenarbeit","status":"publish","type":"post","link":"https:\/\/schloetter-group.com\/de\/zur-feier-von-60-jahren-erfolgreicher-zusammenarbeit\/","title":{"rendered":"Zur Feier von 60 Jahren erfolgreicher Zusammenarbeit"},"content":{"rendered":"\n<p>Zur Feier von 60 Jahren erfolgreicher Zusammenarbeit besucht ein Schl\u00f6tter-Team den Hauptsitz von Leybold in Tokio. Ziel dieses mit Spannung erwarteten Treffens zwischen <a href=\"https:\/\/www.linkedin.com\/company\/leybold-vacuum\/\">Leybold<\/a> &#8211; SECO und Schl\u00f6tter ist es, unsere gemeinsamen Fortschritte und Errungenschaften zu feiern und nach weiteren M\u00f6glichkeiten f\u00fcr eine verst\u00e4rkte Zusammenarbeit in der Oberfl\u00e4chentechnik zu suchen. <\/p>\n\n\n\n<p><br>Mit \u00fcber einem Jahrhundert Erfahrung bietet Leybold L\u00f6sungen durch die Kombination von intelligenten L\u00f6sungen, einem umfangreichen Netzwerk und Fachwissen. Genau wie Schl\u00f6tter ist auch Leybold bestrebt, leistungsstarke und innovative L\u00f6sungen zu liefern, die den individuellen Anforderungen der Kunden gerecht werden und gleichzeitig die allgemeinen Branchentrends widerspiegeln. Als Fachh\u00e4ndler f\u00fcr Werkzeug- und Industriemaschinen verf\u00fcgt Leybold \u00fcber ein umfangreiches Know-how und ein gro\u00dfes Netzwerk, das \u00fcber viele Jahre hinweg aufgebaut wurde, um umfassende Gesch\u00e4ftsl\u00f6sungen anzubieten.  <\/p>\n\n\n\n<p><br>In unseren freundschaftlichen Gespr\u00e4chen ging es darum, die Bereiche der Zusammenarbeit zu erweitern, neue Innovationen zu erforschen und Synergien zu identifizieren, die beiden Unternehmen helfen werden, die sich entwickelnden Anforderungen des globalen Marktes zu erf\u00fcllen. Gemeinsam wollen wir unser geb\u00fcndeltes Fachwissen nutzen, um innovative L\u00f6sungen anzubieten und die Grenzen der Technologie im Bereich der Oberfl\u00e4chenbearbeitung zu erweitern. Schl\u00f6tter und Leybold verbindet nicht nur eine gesunde Gesch\u00e4ftsbeziehung, sondern auch gemeinsame Grundwerte wie das Engagement f\u00fcr Pr\u00e4zision und Nachhaltigkeit: Unsere Visionen f\u00fcr die Zukunft sind klar aufeinander abgestimmt.  <\/p>\n\n\n\n<p><br>Dieses Treffen unterstreicht nicht nur den Wert der langfristigen Partnerschaft zwischen unseren Unternehmen &#8211; und L\u00e4ndern &#8211; sondern spiegelt auch unser Engagement f\u00fcr den Aufbau dauerhafter Beziehungen wider, die den Fortschritt vorantreiben. Schl\u00f6tter ist stolz auf seine historischen Bindungen zu Leybold und freut sich auf viele weitere Jahrzehnte der Zusammenarbeit und des gemeinsamen Erfolgs. <\/p>\n\n\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zur Feier von 60 Jahren erfolgreicher Zusammenarbeit besucht ein Schl\u00f6tter-Team den Hauptsitz von Leybold in Tokio. Ziel dieses mit Spannung erwarteten Treffens zwischen Leybold &#8211; SECO und Schl\u00f6tter ist es, unsere gemeinsamen Fortschritte und Errungenschaften zu feiern und nach weiteren M\u00f6glichkeiten f\u00fcr eine verst\u00e4rkte Zusammenarbeit in der Oberfl\u00e4chentechnik zu suchen. <\/p>\n","protected":false},"author":4,"featured_media":2874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/schloetter-group.com\/de\/wp-json\/wp\/v2\/posts\/2878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schloetter-group.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schloetter-group.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schloetter-group.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/schloetter-group.com\/de\/wp-json\/wp\/v2\/comments?post=2878"}],"version-history":[{"count":0,"href":"https:\/\/schloetter-group.com\/de\/wp-json\/wp\/v2\/posts\/2878\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schloetter-group.com\/de\/wp-json\/wp\/v2\/media\/2874"}],"wp:attachment":[{"href":"https:\/\/schloetter-group.com\/de\/wp-json\/wp\/v2\/media?parent=2878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schloetter-group.com\/de\/wp-json\/wp\/v2\/categories?post=2878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schloetter-group.com\/de\/wp-json\/wp\/v2\/tags?post=2878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}